﻿{"id":22954,"date":"2022-06-09T15:26:40","date_gmt":"2022-06-09T20:26:40","guid":{"rendered":"https:\/\/www.supertransporte.gov.co\/?p=22954"},"modified":"2022-06-09T15:26:40","modified_gmt":"2022-06-09T20:26:40","slug":"gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras","status":"publish","type":"post","link":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/","title":{"rendered":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:8vw;--awb-padding-left:8vw;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-color:#ffffff;--awb-bg-color-hover:#ffffff;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:rgba(224,222,222,0);border-color:rgba(224,222,222,0);border-top-width:1px;border-bottom-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><!DOCTYPE html>\n<html>\n  <head>\n    <meta charset=\"utf-8\">\n    <p style=\"text-align: left;\"><span style=\"color: #004884; font-size: 14px;\"><span style=\"text-decoration: underline;\"><a style=\"color: #004884; text-decoration: underline;\" title=\"Acceder a la p\u00e1gina\" href=\"https:\/\/www.supertransporte.gov.co\/\">Inicio<\/a><\/span> \/ <span style=\"text-decoration: underline;\"><a style=\"color: #004884; text-decoration: underline;\" title=\"Acceder a la p\u00e1gina\" href=\"https:\/\/www.supertransporte.gov.co\/index.php\/sala-de-prensa-2022\/\"><strong>Noticias 2022<\/strong><\/a><\/span><\/span><\/p>\n  <\/head>\n <\/html><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-color:rgba(234,233,233,0);--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:8vw;--awb-padding-left:8vw;--awb-background-color:#ffffff;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_4 3_4 fusion-three-fourth fusion-column-first\" style=\"--awb-bg-color:#ffffff;--awb-bg-color-hover:#ffffff;--awb-bg-size:cover;width:75%;width:calc(75% - ( ( 4% ) * 0.75 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><!DOCTYPE html>\n<html>\n  <head>\n    <meta charset=\"utf-8\">\n    <h1 style=\"text-align: left;\"><strong>Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras<\/strong><\/h1>\n  <\/head>\n <\/html><!DOCTYPE html>\n<html>\n  <head>\n    <meta charset=\"utf-8\">\n    <p>Junio 09, 2022 | Por: Comunicaciones Supertransporte<\/p>\n  <\/head>\n <\/html><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:1em;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:rgba(224,222,222,0);border-color:rgba(224,222,222,0);border-top-width:1px;border-bottom-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><ul>\n<li><em>Entre el 17 de junio al 31 de julio se prev\u00e9 que se movilicen 37.006.000 veh\u00edculos (paso peaje) de los cuales 11.<\/em><em>243.686 veh\u00edculos se estima que lo hagan entre los puentes festivos <\/em><em>de <\/em><em>Corpus Christi, Sagrado Coraz\u00f3n y San Pedro y San Pablo.<\/em><\/li>\n<li><em>Por los aeropuertos del pa\u00eds de prev\u00e9 una movilizaci\u00f3n de 5.697.822 pasajeros y en las terminales terrestres de 13.<\/em><em>531.000<\/em><em> pasajeros.<\/em><\/li>\n<li><em>La Agencia Nacional de Seguridad Vial estar\u00e1 presente durante la temporada de vacaciones en 12 departamentos y 60 municipios con la estrategia Ruta Nacional por la Seguridad Vial.<\/em><\/li>\n<li><em>Para consultar el estado de las v\u00edas en tiempo real podr\u00e1 hacerlo a trav\u00e9s del #767.<\/em><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>(@MintransporteCo). <\/strong>Para brindar una adecuada movilidad durante la temporada alta de mitad de a\u00f1o, el Gobierno Nacional lanz\u00f3 la estrategia vacaciones seguras en la que todas las entidades adscritas al Ministerio de Transporte y la Direcci\u00f3n de Tr\u00e1nsito y Transporte de la Polic\u00eda Nacional, se unen para fortalecer diferentes acciones para prevenir la siniestralidad y facilitar la movilidad por los diferentes medios de transporte.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>Entre el 17 de junio y el 31 de julio se prev\u00e9 que 37.006.000 veh\u00edculos se movilicen por los principales corredores viales del pa\u00eds (paso peaje) y de estos 11.243.686 se estima que se movilicen durante los tres puentes festivos, para Corpus Christi se espera que transiten 3.654.985 veh\u00edculos, mientras que para el del Sagrado Coraz\u00f3n, se proyecta una movilizaci\u00f3n de 4.059.095 automotores y para el puente festivo de San Pedro y San Pablo se proyecta una movilizaci\u00f3n de 3.529.606 veh\u00edculos (paso peaje).<\/p>\n<p>\u00a0<\/p>\n<p>La ministra de Transporte, \u00c1ngela Mar\u00eda Orozco, manifest\u00f3: \u201c<em>El sector Transporte, est\u00e1 preparado para que todos los colombianos puedan disfrutar de unas vacaciones seguras, por eso a partir del 11 de junio estaremos trabajando con estrategias preventivas previo al inicio de vacaciones el pr\u00f3ximo 17 de junio. Nuestro compromiso, desde el primer d\u00eda, fue conectar las vidas de los ciudadanos, acercarlos a lo que m\u00e1s quieren y necesitan. Es con hechos que seguiremos trabajando para lograrlo hasta el \u00faltimo d\u00eda de nuestra gesti\u00f3n, y sabemos que los colombianos nos acompa\u00f1ar\u00e1n en esta labor\u201d. <\/em><\/p>\n<p>\u00a0<\/p>\n<p>La Direcci\u00f3n de Tr\u00e1nsito y Transporte dispuso cerca de 6.100 mujeres y hombres en 266 tramos con 12.400 kil\u00f3metros en la v\u00eda nacional que velar\u00e1n por la seguridad, movilidad y prevenci\u00f3n de la siniestralidad, mediante 14 puntos pedag\u00f3gicos y 110 \u00e1reas de prevenci\u00f3n, brindando asistencia t\u00e9cnico-mec\u00e1nica y humana a los actores viales.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>\u201cTambi\u00e9n desplegaremos un componente log\u00edstico en las carreteras nacionales con 695 patrullas vigilando la movilidad y atenci\u00f3n inmediata de siniestros viales, 3.053 motocicletas ubicadas en puntos estrat\u00e9gicos, 69 gr\u00faas, 16 veh\u00edculos blindados t\u00e1cticos, 4 veh\u00edculos de rescate, 2 centros de comando y control m\u00f3vil (drones), 262 alcohosensores, 174 radares de velocidad, 30 estaciones totales de topograf\u00eda, 62 unidades m\u00f3viles de criminal\u00edstica y 5 buses aula\u201d, <\/em>asegur\u00f3 el Director de la Direcci\u00f3n de Tr\u00e1nsito y Transporte, Mayor General Juan Alberto Libreros.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>La Agencia Nacional de Seguridad Vial estar\u00e1 presente durante la temporada de vacaciones en 12 departamentos y 60 municipios con la estrategia Ruta Nacional por la Seguridad Vial, donde a trav\u00e9s de actividades en calle y pedag\u00f3gicas se espera generar una conciencia sobre la corresponsabilidad en las v\u00edas, el uso de elementos de protecci\u00f3n, importancia de las revisiones preventivas del veh\u00edculo antes de emprender los desplazamientos. Adem\u00e1s, tendr\u00e1 activas 11 mesas de articulaci\u00f3n con autoridades municipales, departamentales y de la Direcci\u00f3n de Tr\u00e1nsito y Transporte en los puentes festivos del Sagrado Coraz\u00f3n y de las fiestas de San Pedro y San Pablo para determinar acciones preventivas que ayuden a prevenir siniestros viales y que incentiven los comportamientos seguros de todos los actores viales.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u201cDesde las investigaciones\u00a0 que realiza la Agencia Nacional de Seguridad Vial, hemos identificado que las tres causas m\u00e1s frecuentes en la siniestralidad del pa\u00eds son:\u00a0 primero,\u00a0 el exceso de velocidad, segundo, el irrespeto a las se\u00f1ales de tr\u00e1nsito como el pare, el sem\u00e1foro y adelantar en zonas prohibidas o por la derecha, y en tercer lugar, conducir bajo efectos de embriaguez, el denominado guayabo o\u00a0 sustancias psicoactivas; por ello en ese orden, nuestro llamado es a tener acciones responsables en las v\u00edas para poder disfrutar de unas vacaciones seguras. Asimismo, hacemos un llamado a las revisiones preventivas de los veh\u00edculos en los que nos vamos a desplazar para minimizar los riesgos y as\u00ed volver a casa sanos y salvos\u201d,<\/em> asegur\u00f3, Luis Lota, director de la Agencia Nacional de Seguridad Vial<em>. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>De acuerdo con la Superintendencia de Transporte, se estima que durante la temporada de vacaciones se movilicen 13.531.000 pasajeros en 1.579.500 veh\u00edculos de transporte terrestre intermunicipal, lo que representa un incremento del 57% frente al a\u00f1o pasado.<\/p>\n<p>.<\/p>\n<p>Para el Superintendente de Transporte, Wilmer Arley Salazar Arias, es importante resaltar que <em>\u201cpara la temporada alta que corresponde a las vacaciones de mitad de a\u00f1o, se ha intensificado la presencia de nuestros colaboradores en 26 terminales, 25 aeropuertos, 5 estaciones de cable y los 17 cuerpos de agua m\u00e1s visitados en esta \u00e9poca. Estaremos atendiendo las peticiones y quejas de los usuarios de todos los modos de transporte y realizando labores de socializaci\u00f3n y orientaci\u00f3n sobre los derechos y los deberes de los usuarios. As\u00ed mismo, recomendamos a los viajeros cumplir con las indicaciones correspondientes para evitar inconvenientes, pues tanto de los empresarios como de los usuarios depende una movilidad con seguridad y legalidad. Es con hechos que estamos cumpli\u00e9ndole al pa\u00eds, como una entidad cercana que escucha a los ciudadanos\u201d.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>En los diversos aeropuertos del pa\u00eds, se estima una movilizaci\u00f3n de cerca de 5.697.822 pasajeros. Las ciudades con mayor movilizaci\u00f3n de pasajeros ser\u00e1n Bogot\u00e1, Medell\u00edn, Barranquilla, Cali, Cartagena, Bucaramanga, Santa Marta, Armenia, Riohacha, Manizales, Pasto y Monter\u00eda.<\/p>\n<p>\u00a0<\/p>\n<p>Para el director general de la Aeron\u00e1utica Civil, Jair Orlando Fajardo, \u201c<em>el pa\u00eds va en camino de una reactivaci\u00f3n segura del transporte a\u00e9reo tanto nacional como internacional, y esta temporada alta no ser\u00e1 la excepci\u00f3n. Desde la Aerocivil vamos a garantizar la movilizaci\u00f3n de cerca de 5.7 millones de pasajeros, de los cuales 3.868.006 se desplazar\u00e1n hacia destinos nacionales y 1.829.816 hacia destinos internacionales. Nuestros equipos t\u00e9cnicos y el Grupo de Atenci\u00f3n al Usuario que hace presencia en los aeropuertos del pa\u00eds estar\u00e1n atentos a servir a quienes lo necesiten\u201d.<\/em><\/p>\n<p>El Instituto Nacional de V\u00edas (INV\u00cdAS) contar\u00e1 con 350 operarios en las 34 estaciones de peaje a su cargo, durante las vacaciones de mitad de a\u00f1o, quienes trabajar\u00e1n distribuidos por turnos, de acuerdo con la demanda de tr\u00e1fico que se presente en cada estaci\u00f3n. Para atender las eventualidades que puedan presentarse en las v\u00edas, las 26 direcciones territoriales del Instituto estar\u00e1n en disponibilidad permanente junto con las 90 administraciones viales disponibles, en las que participan 3.600 microempresarios entre operarios, t\u00e9cnicos e ingenieros, ubicados en 269 frentes y encargados del mantenimiento rutinario. Adicionalmente, la entidad cuenta con herramientas de informaci\u00f3n para consultar el estado de las v\u00edas en tiempo real como la l\u00ednea gratuita #767 (desde cualquier celular), el mapa de carreteras y el portal web Viajero Seguro, a los que se puede ingresar desde la p\u00e1gina de la entidad www.invias.gov.co.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Por su parte, la Agencia Nacional de Infraestructura (ANI) realizar\u00e1 seguimiento permanente a cada uno de los corredores viales a cargo de la entidad, para esto le solicit\u00f3 a cada una de las concesiones carreteras, un reporte de las novedades que se presenten en sus v\u00edas en tiempo real para estar al tanto y hacer seguimiento e Informar a los usuarios qu\u00e9 hacer en caso de presentarse una emergencia vial a causa de la temporada de lluvias. En caso de presentarse alguna novedad, los corredores concesionados siempre disponen de un equipo de maquinaria amarilla (retroexcavadoras, volquetas) pendiente las 24 horas. Los servicios de inspecci\u00f3n vial, ambulancia, carro-taller y gr\u00faa, junto a la Polic\u00eda de Tr\u00e1nsito y Transporte, se encuentran dispuestos para atender los eventos que se requieran, en las v\u00edas concesionadas.<\/p>\n<p>\u00a0<\/p>\n<p>De esta manera, el Gobierno Nacional a trav\u00e9s del Ministerio de Transporte, ratifica su compromiso por una movilidad segura de los usuarios en las diversas regiones del pa\u00eds, implementando estrategias como la de hoy para brindar una unas vacaciones seguras.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:rgba(224,222,222,0);border-color:rgba(224,222,222,0);border-top-width:1px;border-bottom-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"--awb-bg-color:#ffffff;--awb-bg-color-hover:#ffffff;--awb-bg-size:cover;width:25%;width:calc(25% - ( ( 4% ) * 0.25 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\"><h3><span style=\"font-size: 20px; color: #004884;\">Leer a continuaci\u00f3n<\/span><\/h3>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:rgba(224,222,222,0);border-color:rgba(224,222,222,0);border-top-width:1px;border-bottom-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-recent-posts fusion-recent-posts-1 avada-container layout-default layout-columns-1\"><section class=\"fusion-columns columns fusion-columns-1 columns-1\"><article class=\"post fusion-column column col col-lg-12 col-md-12 col-sm-12\"><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-12-16T12:23:53-05:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/las-zonas-portuarias-de-colombia-movilizaron-858-millones-de-toneladas-de-carga-con-un-crecimiento-del-3-frente-al-ano-anterior\/\">Las zonas portuarias de Colombia movilizaron 85,8 millones de toneladas de carga, con un crecimiento del 3% frente al a\u00f1o anterior<\/a><\/h4><p class=\"meta\">By <span class=\"vcard\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"fusion-inline-sep\">|<\/span><span class=\"updated\" style=\"display:none;\">2022-12-16T12:23:53-05:00<\/span><span>diciembre 16th, 2022<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/article><article class=\"post fusion-column column col col-lg-12 col-md-12 col-sm-12\"><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-12-19T11:42:48-05:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/supertransporte-otorga-reconocimientos-a-22-empresas-de-transporte-fluvial-que-cumplen-100-con-la-normatividad-vigente-para-el-sector\/\">SuperTransporte otorga reconocimientos a 22 empresas de transporte fluvial que cumplen 100% con la normatividad vigente para el sector<\/a><\/h4><p class=\"meta\">By <span class=\"vcard\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"fusion-inline-sep\">|<\/span><span class=\"updated\" style=\"display:none;\">2022-12-19T11:42:48-05:00<\/span><span>diciembre 13th, 2022<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/article><article class=\"post fusion-column column col col-lg-12 col-md-12 col-sm-12\"><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2022-12-07T16:12:44-05:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/transporte-y-ambiente-unidos-para-garantizar-movilidad-segura-y-sin-trafico-de-fauna-silvestre-en-temporada-de-fin-de-ano\/\">Transporte y ambiente unidos para garantizar movilidad segura y sin tr\u00e1fico de fauna silvestre en temporada de fin de a\u00f1o<\/a><\/h4><p class=\"meta\">By <span class=\"vcard\"><span class=\"fn\"><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/\" title=\"Entradas de Comunicaciones Supertransporte\" rel=\"author\">Comunicaciones Supertransporte<\/a><\/span><\/span><span class=\"fusion-inline-sep\">|<\/span><span class=\"updated\" style=\"display:none;\">2022-12-07T16:12:44-05:00<\/span><span>diciembre 7th, 2022<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/article><\/section><div class=\"pagination clearfix\"><span class=\"current\">1<\/span><a href=\"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/22954\/page\/2\/\" class=\"inactive\">2<\/a><a class=\"pagination-next\" rel=\"next\" href=\"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/22954\/page\/2\/\"><span class=\"page-text\">Siguiente<\/span><span class=\"page-next\"><\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":22955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,153],"tags":[],"class_list":["post-22954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comun-junio-2022","category-comunicaciones-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/\" \/>\n<meta property=\"og:site_name\" content=\"Superintendencia de Transporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/Supertransporte\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T20:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones Supertransporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@supertransporte\" \/>\n<meta name=\"twitter:site\" content=\"@supertransporte\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones Supertransporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/\"},\"author\":{\"name\":\"Comunicaciones Supertransporte\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#\\\/schema\\\/person\\\/b664f3388ed6f9cd17a76072c53335e8\"},\"headline\":\"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras\",\"datePublished\":\"2022-06-09T20:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/\"},\"wordCount\":3419,\"publisher\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220609-WA0143.jpg\",\"articleSection\":[\"Comun - Junio 2022\",\"Comunicaciones 2022\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/\",\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/\",\"name\":\"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220609-WA0143.jpg\",\"datePublished\":\"2022-06-09T20:26:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220609-WA0143.jpg\",\"contentUrl\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220609-WA0143.jpg\",\"width\":1280,\"height\":853,\"caption\":\"imagen decorativa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/comunicaciones-2022\\\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#website\",\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/\",\"name\":\"Superintendencia de Transporte\",\"description\":\"Inspecci\u00f3n, vigilancia y control en la prestaci\u00f3n del servicio p\u00fablico de transporte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#organization\",\"name\":\"Superintendencia de Transporte\",\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/2-1.png\",\"contentUrl\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/2-1.png\",\"width\":114,\"height\":114,\"caption\":\"Superintendencia de Transporte\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Supertransporte\\\/\",\"https:\\\/\\\/x.com\\\/supertransporte\",\"https:\\\/\\\/www.instagram.com\\\/supertransporte_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC0mcvyJ7WF-Dz884ZiIifHg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/supertransporte\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/193210255@N04\\\/albums\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/#\\\/schema\\\/person\\\/b664f3388ed6f9cd17a76072c53335e8\",\"name\":\"Comunicaciones Supertransporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones Supertransporte\"},\"url\":\"https:\\\/\\\/www.supertransporte.gov.co\\\/index.php\\\/author\\\/comunicaciones-supertransporte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte","og_url":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/","og_site_name":"Superintendencia de Transporte","article_publisher":"https:\/\/es-la.facebook.com\/Supertransporte\/","article_published_time":"2022-06-09T20:26:40+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg","type":"image\/jpeg"}],"author":"Comunicaciones Supertransporte","twitter_card":"summary_large_image","twitter_creator":"@supertransporte","twitter_site":"@supertransporte","twitter_misc":{"Escrito por":"Comunicaciones Supertransporte","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#article","isPartOf":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/"},"author":{"name":"Comunicaciones Supertransporte","@id":"https:\/\/www.supertransporte.gov.co\/#\/schema\/person\/b664f3388ed6f9cd17a76072c53335e8"},"headline":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras","datePublished":"2022-06-09T20:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/"},"wordCount":3419,"publisher":{"@id":"https:\/\/www.supertransporte.gov.co\/#organization"},"image":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg","articleSection":["Comun - Junio 2022","Comunicaciones 2022"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/","url":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/","name":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras - Superintendencia de Transporte","isPartOf":{"@id":"https:\/\/www.supertransporte.gov.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#primaryimage"},"image":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg","datePublished":"2022-06-09T20:26:40+00:00","breadcrumb":{"@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#primaryimage","url":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg","contentUrl":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2022\/06\/IMG-20220609-WA0143.jpg","width":1280,"height":853,"caption":"imagen decorativa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.supertransporte.gov.co\/index.php\/comunicaciones-2022\/gobierno-nacional-lanza-estrategia-integral-de-movilidad-y-seguridad-vial-para-garantizar-unas-vacaciones-seguras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.supertransporte.gov.co\/"},{"@type":"ListItem","position":2,"name":"Gobierno Nacional lanza estrategia integral de movilidad y seguridad vial para garantizar unas vacaciones seguras"}]},{"@type":"WebSite","@id":"https:\/\/www.supertransporte.gov.co\/#website","url":"https:\/\/www.supertransporte.gov.co\/","name":"Superintendencia de Transporte","description":"Inspecci\u00f3n, vigilancia y control en la prestaci\u00f3n del servicio p\u00fablico de transporte","publisher":{"@id":"https:\/\/www.supertransporte.gov.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supertransporte.gov.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.supertransporte.gov.co\/#organization","name":"Superintendencia de Transporte","url":"https:\/\/www.supertransporte.gov.co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.supertransporte.gov.co\/#\/schema\/logo\/image\/","url":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2024\/06\/2-1.png","contentUrl":"https:\/\/www.supertransporte.gov.co\/wp-content\/uploads\/2024\/06\/2-1.png","width":114,"height":114,"caption":"Superintendencia de Transporte"},"image":{"@id":"https:\/\/www.supertransporte.gov.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Supertransporte\/","https:\/\/x.com\/supertransporte","https:\/\/www.instagram.com\/supertransporte_oficial\/","https:\/\/www.youtube.com\/channel\/UC0mcvyJ7WF-Dz884ZiIifHg","https:\/\/www.linkedin.com\/company\/supertransporte","https:\/\/www.flickr.com\/photos\/193210255@N04\/albums\/"]},{"@type":"Person","@id":"https:\/\/www.supertransporte.gov.co\/#\/schema\/person\/b664f3388ed6f9cd17a76072c53335e8","name":"Comunicaciones Supertransporte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f5df8f32079fcb14bc5556a5d7118a2daf56a2c3c97aba3227262678c5976fc?s=96&d=mm&r=g","caption":"Comunicaciones Supertransporte"},"url":"https:\/\/www.supertransporte.gov.co\/index.php\/author\/comunicaciones-supertransporte\/"}]}},"_links":{"self":[{"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/22954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/comments?post=22954"}],"version-history":[{"count":1,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/22954\/revisions"}],"predecessor-version":[{"id":22956,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/posts\/22954\/revisions\/22956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/media\/22955"}],"wp:attachment":[{"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/media?parent=22954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/categories?post=22954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.supertransporte.gov.co\/index.php\/wp-json\/wp\/v2\/tags?post=22954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}